{"id":2253,"date":"2020-10-12T01:40:44","date_gmt":"2020-10-12T05:40:44","guid":{"rendered":"https:\/\/leoprd.ca\/?post_type=product&#038;p=2253"},"modified":"2025-03-01T12:36:19","modified_gmt":"2025-03-01T16:36:19","slug":"rush-bench","status":"publish","type":"product","link":"https:\/\/leoprd.ca\/fr\/product\/rush-bench\/","title":{"rendered":"Banc Rush"},"content":{"rendered":"<p>This modern designed upholstered bench is solid beech wood with a high quality upholstered top. Gorgeous finished frame. Simple line design creates a clean look. Great for any space <a href=\"https:\/\/leoprd.ca\/fr\/categorie-produit\/living-room-furniture\/\"><em>espace de vie<\/em><\/a>, <a href=\"https:\/\/leoprd.ca\/fr\/categorie-produit\/dining-room-furniture\/\"><em>salle \u00e0 manger<\/em><\/a>, bedroom or entrance hallway. it perfectly matches with our <em><a href=\"https:\/\/leoprd.ca\/fr\/product\/elena-dinning-table\/\">Elena dining table<\/a><\/em>.<\/p>\n<p><span style=\"font-size: 16px;\"><div class='yrm-content yrm-content-1 yrm-content-hide' id='yrm-cH9l0' data-id='1' data-show-status='false' data-after-action='' style=\"visibility: hidden;height: 0;\">\n\t\t\t<div id='yrm-inner-content-yrm-cH9l0' class='yrm-inner-content-wrapper yrm-cntent-1'><\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>bois de h\u00eatre<\/strong><\/h3>\n<p><strong>le bois de h\u00eatre<\/strong>\u00a0est un bois a fins grains qui a une couleur  orange clair vers le  saumon. Nous aimons ses motifs de pores distincts. Le bois est souvent utilis\u00e9 pour faire du bois solide.<\/p>\n<p>Un des avantages a utiliser\u00a0<strong>le bois de h\u00eatre<\/strong>\u00a0pour les meubles c'est qu'il est indolore. C'est le meilleur choix si vous ne souhaitez pas sentir l'odeur du bois dans votre salon ou votre chambre,   ou si vous aimez un meuble de couleur claire.<\/p>\n<h3>voici 5 avantages du bois de h\u00eatre pour les meubles<\/h3>\n<h6>flexible<\/h6>\n<p>Le bois de h\u00eatre est utilis\u00e9 pour la fabrication de meubles courb\u00e9s, puisqu'il est facilement maniable, il est le parfait candidat pour presque tout - chaises, armoires, sol, cuill\u00e8res, planches a d\u00e9couper, meme les goblets. Il est tr\u00e8s facile de travailler avec le bois de h\u00eatre dans ce type d'industrie.<\/p>\n<h6>durable<\/h6>\n<p>Appartenant a la cat\u00e9gorie des bois  \"r\u00e9sistants a l'usure\", le bois dure du h\u00eatre n'est pas poreux, a une solide densit\u00e9 et une surface robuste. cela se traduit par sa r\u00e9sistance a la pression, a l'ecaillage et au gonflement, plus que certaines autres vari\u00e9t\u00e9s de bois<\/p>\n<h6>absorbant de choc<\/h6>\n<p>Avec sa texture uniforme, le bois de h\u00eatre a grain droit offre une significative r\u00e9sistance a la pression, parce que dur, lourd et robuste. Retenez, que le bois de h\u00eatre est aussi appropri\u00e9 pour le sol,  puisqu'il supporte le poids et la force des forts impacts.<\/p>\n<h6>entretien facile<\/h6>\n<p>le bois de h\u00eatre l\u00e9g\u00e8rement \u00e9tuv\u00e9 est souvent utilis\u00e9 pour illuminer le grain naturel, le fini, et l'uniformit\u00e9 des couleurs du bois. Puisqu'il a des propri\u00e9t\u00e9s de longue dur\u00e9e, le meuble en bois de h\u00eatre r\u00e9sistera a l'usure du temps, et aura une bonne apparence meme apr\u00e8s plusieurs ann\u00e9es. En cas de dommages esth\u00e9tiques graves, il suffit de poncer les bords pour faire l'affaire.<\/p>\n<h3><strong>meuble en tissu polyester<\/strong><\/h3>\n<p>Le polyester a certainement sa place dans l'ameublement mondial grace a ses nombreux avantages tels que les options de rembourrage naturel. Ce qui le rend optimal, c'est un tissu abordable qui peut durer aussi bien pour l'usage interne qu'externe.<\/p>\n<p>voici tous les avantages d'acheter des meubles rembourr\u00e9s de polyester :<\/p>\n<ul>\n<li>\n<h6>facile d'entretien<\/h6>\n<\/li>\n<\/ul>\n<p>Le polyester est l'un des tissus les plus faciles a nettoyer, cela parce qu'aucune tache ne peut p\u00e9n\u00e9trer le tissu, contrairement au coton, mais la tache reste sur la surface, ce qui facilite le travail  avec ce type tissu en cas de d\u00e9sagr\u00e9ment dans la piece. C'est aussi un des tissu les plus faciles a entretenir. Le cuir exige une complexit\u00e9 dans le traitement afin de le garder dans une bonne condition. En comparaison, le polyester est le plus simple.<\/p>\n<ul>\n<li>\n<h6>disponible en plusieurs couleurs<\/h6>\n<\/li>\n<\/ul>\n<p>Ce qui est agr\u00e9able avec le polyester, c'est qu'il est possible d'obtenir un meuble en polyester et dans toutes les d\u00e9clinaisons de couleurs que vous d\u00e9sirez. Les tissus naturels, par ailleurs viennent avec un nombre limit\u00e9 de couleurs naturelles. Si vous d\u00e9sirez un canap\u00e9 en polyester de couleur naturel, ou qui s'accorde a la couleur de votre espace de vie, il ya de nombreuses couleurs disponibles en ligne peu importe le vendeur que vous aurez a visiter.<\/p>\n<ul>\n<li>\n<h6>durable<\/h6>\n<\/li>\n<\/ul>\n<p>Grace a la nature synth\u00e9tique du polyester, il est consid\u00e9r\u00e9 comme le type de rembourrage qui peut perdurer. En fait, il est un des meilleurs choix pour les meubles ext\u00e9rieurs. Le polyester est tapellant a l'eau et un r\u00e9sistant a la moisissure. La couleur sur le polyester ne ternit pas, donc les propri\u00e9taires n'ont pas a se soucier de son exposition au soleil.<\/p>\n<ul>\n<li>\n<h6>L\u00e9ger<\/h6>\n<\/li>\n<\/ul>\n<p>Certains propri\u00e9taires craignent que les meubles soient difficiles \u00e0 d\u00e9placer. Alors que tous les meubles dot\u00e9s d'une structure d\u00e9cente sont consid\u00e9r\u00e9s comme lourds, les meubles en polyester seront toujours l'un des types de meubles les plus l\u00e9gers \u00e0 transporter. Vous pouvez facilement faire cette distinction en touchant un coussin en polyester et en constatant qu'il est l\u00e9ger et a\u00e9r\u00e9 au toucher. D'autres tissus comme le velours ou la rayonne sont consid\u00e9r\u00e9s comme un peu plus lourds, et les propri\u00e9taires ne se rendent pas compte de la diff\u00e9rence jusqu'\u00e0 ce qu'ils doivent les d\u00e9placer.<\/p>\n<ul>\n<li>\n<h6>Belle texture<\/h6>\n<\/li>\n<\/ul>\n<p>Le polyester peut aussi avoir sa propre personnalit\u00e9. Le polyester est tiss\u00e9 dans une texture crois\u00e9e, ce qui lui conf\u00e8re une certaine personnalit\u00e9 plut\u00f4t qu'une couleur unie et plate. Cette texture est agr\u00e9able \u00e0 regarder et \u00e0 toucher, ce qui fait que vous n'obtenez pas un tissu fade en raison de son caract\u00e8re synth\u00e9tique et de son prix abordable.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 16px;\"><\/div>\n\t\t<\/div><div class='yrm-btn-wrapper yrm-btn-wrapper-1 yrm-more-button-wrapper'\n\t\tdata-custom-more-class-name='' data-custom-less-class-name=''><span title='' data-less-title='' data-more-title='' class='yrm-toggle-expand  yrm-toggle-expand-1' data-rel='yrm-cH9l0' data-more='Read More' data-less='Read Less'><span class='yrm-text-wrapper yrm-text-wrapper-custom-dimensions'><span class=\"yrm-button-text-1 yrm-button-text-span\">Lire la suite<\/span><\/span><\/span><\/div><\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>This modern designed upholstered bench is solid beech wood with a high quality upholstered top. Gorgeous finished frame. Simple line design creates a clean look.<\/p>","protected":false},"featured_media":7766,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[66,67,59],"product_tag":[183],"class_list":["post-2253","product","type-product","status-publish","has-post-thumbnail","product_cat-benches","product_cat-dining-room-furniture","product_cat-living-room-furniture","product_tag-dbq-variety-of-colors","pa_upholstery-athen-15","pa_upholstery-enzo-102","pa_upholstery-enzo-602","pa_wood-color-natural","pa_wood-color-walnut","desktop-align-center","tablet-align-center","mobile-align-center","first","outofstock","taxable","shipping-taxable","purchasable","product-type-variable","wvs-archive-product-wrapper"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Upholstered Bench | Buy Online &amp; In-store | LEOPARD Furniture<\/title>\n<meta name=\"description\" content=\"This modern designed upholstered bench is solid beech wood with a high quality upholstered top. Simple line design creates a clean look.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leoprd.ca\/fr\/product\/rush-bench\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rush Bench\" \/>\n<meta property=\"og:description\" content=\"This modern designed upholstered bench is solid beech wood with a high quality upholstered top. Simple line design creates a clean look.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leoprd.ca\/fr\/product\/rush-bench\/\" \/>\n<meta property=\"og:site_name\" content=\"LEOPARD Furniture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/leoprd.ca\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-01T16:36:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leoprd.ca\/wp-content\/uploads\/2022\/02\/Rush-enzo602.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data1\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/leoprd.ca\\\/fr\\\/product\\\/rush-bench\\\/\",\"url\":\"https:\\\/\\\/leoprd.ca\\\/fr\\\/product\\\/rush-bench\\\/\",\"name\":\"Upholstered Bench | Buy Online & In-store | LEOPARD Furniture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leoprd.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leoprd.ca\\\/fr\\\/product\\\/rush-bench\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leoprd.ca\\\/fr\\\/product\\\/rush-bench\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leoprd.ca\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Rush-enzo602.jpg\",\"datePublished\":\"2020-10-12T05:40:44+00:00\",\"dateModified\":\"2025-03-01T16:36:19+00:00\",\"description\":\"This modern designed upholstered bench is solid beech wood with a high quality upholstered top. Simple line design creates a clean look.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leoprd.ca\\\/fr\\\/product\\\/rush-bench\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leoprd.ca\\\/fr\\\/product\\\/rush-bench\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/leoprd.ca\\\/fr\\\/product\\\/rush-bench\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leoprd.ca\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Rush-enzo602.jpg\",\"contentUrl\":\"https:\\\/\\\/leoprd.ca\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Rush-enzo602.jpg\",\"width\":1600,\"height\":1600,\"caption\":\"modern bench rush gray\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leoprd.ca\\\/fr\\\/product\\\/rush-bench\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leoprd.ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/leoprd.ca\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rush Bench\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leoprd.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/leoprd.ca\\\/fr\\\/\",\"name\":\"LEOPARD Furniture\",\"description\":\"Furniture store\",\"publisher\":{\"@id\":\"https:\\\/\\\/leoprd.ca\\\/fr\\\/#organization\"},\"alternateName\":\"Meubles L\u00c9OPARD\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leoprd.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/leoprd.ca\\\/fr\\\/#organization\",\"name\":\"LEOPARD Furniture\",\"alternateName\":\"Meuble LEOPARD\",\"url\":\"https:\\\/\\\/leoprd.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/leoprd.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/leoprd.ca\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-silver-mid.png\",\"contentUrl\":\"https:\\\/\\\/leoprd.ca\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-silver-mid.png\",\"width\":400,\"height\":400,\"caption\":\"LEOPARD Furniture\"},\"image\":{\"@id\":\"https:\\\/\\\/leoprd.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/leoprd.ca\",\"https:\\\/\\\/mastodon.social\\\/@leopardfurniture\",\"https:\\\/\\\/www.instagram.com\\\/leopardcanada\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/leopard-trading-company\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@leopardcanada\"],\"description\":\"LEOPARD Furniture, a Canadian-born legacy headquartered in the vibrant city of Montreal, Quebec, with a prime location in Brossard. At LEOPARD, we curate the finest furniture selections from premium-quality and esteemed international manufacturers. Our commitment lies in customization and the importation of high-end products. Our Commitment to Quality and Excellence Reliability You Can Trust Built on five pillars \u2013 trust, reliability, customer satisfaction, excellence, and innovation \u2013 LEOPARD Furniture has been a reliable name in the furniture industry. Our commitment to quality and transparency ensures that every piece you select resonates with durability and aesthetic brilliance. Award-Winning Designs Immerse yourself in a world of award-winning designs curated to elevate your living spaces. Our products have been recognized for their innovation and style, showcasing a commitment to staying ahead of design trends. Unparalleled Interior Design Services Personalized 3D Design and AR Experience Embark on a personalized interior design journey with LEOPARD Furniture. Our team, equipped with cutting-edge technology, offers 3D design and Augmented Reality (AR) experiences, allowing you to visualize your dream space before making a decision. LEOPARD Furniture is a furniture store, not just a furniture store; we are creators of lifestyle. Every piece tells a story, and we invite you to be a part of this narrative. Visit our showroom in Brossard or explore our online gallery.\",\"email\":\"info@leoprd.ca\",\"telephone\":\"+1 (514) 655-8447\",\"legalName\":\"LEOPARD CA INC.\",\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/leoprd.ca\\\/fr\\\/exchange-return-and-refund\\\/\"}}]}<\/script>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LEO13564\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Upholstered Bench | Buy Online &amp; In-store | LEOPARD Furniture","description":"This modern designed upholstered bench is solid beech wood with a high quality upholstered top. Simple line design creates a clean look.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leoprd.ca\/fr\/product\/rush-bench\/","og_locale":"fr_CA","og_type":"article","og_title":"Rush Bench","og_description":"This modern designed upholstered bench is solid beech wood with a high quality upholstered top. Simple line design creates a clean look.","og_url":"https:\/\/leoprd.ca\/fr\/product\/rush-bench\/","og_site_name":"LEOPARD Furniture","article_publisher":"https:\/\/www.facebook.com\/leoprd.ca","article_modified_time":"2025-03-01T16:36:19+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/leoprd.ca\/wp-content\/uploads\/2022\/02\/Rush-enzo602.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/leoprd.ca\/fr\/product\/rush-bench\/","url":"https:\/\/leoprd.ca\/fr\/product\/rush-bench\/","name":"Upholstered Bench | Buy Online &amp; In-store | LEOPARD Furniture","isPartOf":{"@id":"https:\/\/leoprd.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leoprd.ca\/fr\/product\/rush-bench\/#primaryimage"},"image":{"@id":"https:\/\/leoprd.ca\/fr\/product\/rush-bench\/#primaryimage"},"thumbnailUrl":"https:\/\/leoprd.ca\/wp-content\/uploads\/2022\/02\/Rush-enzo602.jpg","datePublished":"2020-10-12T05:40:44+00:00","dateModified":"2025-03-01T16:36:19+00:00","description":"This modern designed upholstered bench is solid beech wood with a high quality upholstered top. Simple line design creates a clean look.","breadcrumb":{"@id":"https:\/\/leoprd.ca\/fr\/product\/rush-bench\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leoprd.ca\/fr\/product\/rush-bench\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/leoprd.ca\/fr\/product\/rush-bench\/#primaryimage","url":"https:\/\/leoprd.ca\/wp-content\/uploads\/2022\/02\/Rush-enzo602.jpg","contentUrl":"https:\/\/leoprd.ca\/wp-content\/uploads\/2022\/02\/Rush-enzo602.jpg","width":1600,"height":1600,"caption":"modern bench rush gray"},{"@type":"BreadcrumbList","@id":"https:\/\/leoprd.ca\/fr\/product\/rush-bench\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leoprd.ca\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/leoprd.ca\/shop\/"},{"@type":"ListItem","position":3,"name":"Rush Bench"}]},{"@type":"WebSite","@id":"https:\/\/leoprd.ca\/fr\/#website","url":"https:\/\/leoprd.ca\/fr\/","name":"Meubles LEOPARD","description":"Magasin de meubles","publisher":{"@id":"https:\/\/leoprd.ca\/fr\/#organization"},"alternateName":"Meubles L\u00c9OPARD","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leoprd.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/leoprd.ca\/fr\/#organization","name":"Meubles LEOPARD","alternateName":"Meuble LEOPARD","url":"https:\/\/leoprd.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/leoprd.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/leoprd.ca\/wp-content\/uploads\/2022\/05\/logo-silver-mid.png","contentUrl":"https:\/\/leoprd.ca\/wp-content\/uploads\/2022\/05\/logo-silver-mid.png","width":400,"height":400,"caption":"LEOPARD Furniture"},"image":{"@id":"https:\/\/leoprd.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/leoprd.ca","https:\/\/mastodon.social\/@leopardfurniture","https:\/\/www.instagram.com\/leopardcanada\/","https:\/\/www.linkedin.com\/company\/leopard-trading-company\/","https:\/\/www.youtube.com\/@leopardcanada"],"description":"Meubles LEOPARD, une entreprise d'origine canadienne dont le si\u00e8ge social est situ\u00e9 dans la ville dynamique de Montr\u00e9al, au Qu\u00e9bec, avec un emplacement de choix \u00e0 Brossard. Chez LEOPARD, nous s\u00e9lectionnons les meubles les plus raffin\u00e9s aupr\u00e8s de fabricants internationaux r\u00e9put\u00e9s et de qualit\u00e9 sup\u00e9rieure. Notre engagement r\u00e9side dans la personnalisation et l'importation de produits haut de gamme. Notre engagement envers la qualit\u00e9 et l'excellence Une fiabilit\u00e9 \u00e0 laquelle vous pouvez vous fier Fond\u00e9e sur cinq piliers - la confiance, la fiabilit\u00e9, la satisfaction de la client\u00e8le, l'excellence et l'innovation - Meubles LEOPARD est un nom fiable dans l'industrie de l'ameublement. Notre engagement en faveur de la qualit\u00e9 et de la transparence garantit que chaque pi\u00e8ce que vous choisissez est synonyme de durabilit\u00e9 et de brillance esth\u00e9tique. Designs prim\u00e9s Plongez dans un monde de designs prim\u00e9s, con\u00e7us pour \u00e9lever vos espaces de vie. Nos produits ont \u00e9t\u00e9 reconnus pour leur innovation et leur style, t\u00e9moignant de notre engagement \u00e0 rester \u00e0 la pointe des tendances en mati\u00e8re de design. Services de design d'int\u00e9rieur in\u00e9gal\u00e9s Design 3D personnalis\u00e9 et exp\u00e9rience AR Embarquez pour un voyage de design d'int\u00e9rieur personnalis\u00e9 avec LEOPARD Furniture. Notre \u00e9quipe, \u00e9quip\u00e9e d'une technologie de pointe, propose des exp\u00e9riences de conception en 3D et de r\u00e9alit\u00e9 augment\u00e9e (RA), vous permettant de visualiser l'espace de vos r\u00eaves avant de prendre une d\u00e9cision. LEOPARD Furniture est un magasin de meubles, pas seulement un magasin de meubles ; nous sommes des cr\u00e9ateurs de style de vie. Chaque pi\u00e8ce raconte une histoire, et nous vous invitons \u00e0 faire partie de ce r\u00e9cit. Visitez notre salle d'exposition \u00e0 Brossard ou explorez notre galerie en ligne.","email":"info@leoprd.ca","telephone":"+1 (514) 655-8447","legalName":"LEOPARD CA INC.","hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/leoprd.ca\/fr\/exchange-return-and-refund\/"}}]},"og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"LEO13564","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/leoprd.ca\/fr\/wp-json\/wp\/v2\/product\/2253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leoprd.ca\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/leoprd.ca\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/leoprd.ca\/fr\/wp-json\/wp\/v2\/comments?post=2253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leoprd.ca\/fr\/wp-json\/wp\/v2\/media\/7766"}],"wp:attachment":[{"href":"https:\/\/leoprd.ca\/fr\/wp-json\/wp\/v2\/media?parent=2253"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/leoprd.ca\/fr\/wp-json\/wp\/v2\/product_brand?post=2253"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/leoprd.ca\/fr\/wp-json\/wp\/v2\/product_cat?post=2253"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/leoprd.ca\/fr\/wp-json\/wp\/v2\/product_tag?post=2253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}